{"id":8464,"date":"2024-04-24T10:12:59","date_gmt":"2024-04-24T08:12:59","guid":{"rendered":"https:\/\/www.dopartners.be\/?page_id=8464"},"modified":"2026-07-08T14:35:56","modified_gmt":"2026-07-08T12:35:56","slug":"xerox-belgique","status":"publish","type":"page","link":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/","title":{"rendered":"Xerox Belgique"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; woodmart_stretch_content=&#8221;section-stretch&#8221; woodmart_bg_position=&#8221;center-center&#8221; el_class=&#8221;hero_title&#8221; woodmart_css_id=&#8221;68d296fe6faf4&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2OGQyOTZmZTZmYWY0Iiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; css=&#8221;.vc_custom_1758631722955{background-image: url(https:\/\/www.dopartners.be\/wp-content\/uploads\/2024\/06\/revolution-xerographique-2-xerox-belgique-dopartners.webp?id=8829) !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column]\n\t\t<div id=\"wd-6a4e0cbbac6f1\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0cbbac6f1 wd-title-color-default wd-title-style-default text-center new_title_h1  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<span class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-l\" >Xerox &amp; Lexmark<br \/>\nBelgique<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\t\t\t<div\n\t\t\t\t\t\tclass=\"wd-el-breadcrumbs wd-wpb wd-rs-68d25d74cc79b text-center\">\n\t\t\t\t\t\t\t<div class=\"yoast-breadcrumb\">\n\t\t\t\t<span><span><a href=\"https:\/\/www.dopartners.be\/fr\/\">Home<\/a><\/span><\/span>\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>   \n\t\t[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1671206711371{margin-bottom: 5vh !important;}&#8221; woodmart_css_id=&#8221;639c97325780f&#8221; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2MzljOTczMjU3ODBmIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;][vc_empty_space height=&#8221;30px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]\n\t\t<div id=\"wd-6a4e061fbe304\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e061fbe304 wd-title-color-primary wd-title-style-simple text-center  wd-width-enabled wd-underline-colored\" style=\"--wd-max-width: 80%;\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xxl\" >Photocopieurs et Solutions Xerox et Lexmark en Belgique bas\u00e9 \u00e0 Bruxelles, D&amp;O Partners \u00e0 votre service<\/h1>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_empty_space height=&#8221;50px&#8221;][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945272483{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bab2e89c8&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmFiMmU4OWM4Iiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6a4e060e25700\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e060e25700 wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Votre expert Xerox et Lexmark en Belgique depuis Bruxelles : Vente, Location et Support<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Depuis plus de 30 ans, \u00e9tabli dans la r\u00e9gion de Bruxelles-Capitale, D&amp;O Partners est votre partenaire de confiance pour toutes vos solutions d&#8217;impression professionnelle en Belgique. En tant que sp\u00e9cialiste des \u00e9quipements et solutions <strong>Xerox et Lexmark en Belgique<\/strong>, nous accompagnons les entreprises dans le choix, le financement, le d\u00e9ploiement et l&#8217;entretien de leurs parcs d&#8217;imprimantes et de photocopieurs multifonctions.<\/p>\n<p>Xerox et Lexmark sont des leaders reconnus, d\u00e9veloppant des \u00e9quipements fiables et innovants pour r\u00e9pondre aux besoins bureautiques en constante \u00e9volution. Que vous cherchiez \u00e0 acheter, louer ou optimiser votre parc d&#8217;impression, D&amp;O Partners vous apporte une expertise locale, de l&#8217;audit initial au support technique continu.<\/p>\n<p>Notre approche est simple : \u00e9coute, transparence et r\u00e9sultats.<\/p>\n<p>Pr\u00eat \u00e0 optimiser votre gestion documentaire ?<\/p>\n<p>Contactez-nous pour une analyse rapide de vos besoins et un devis personnalis\u00e9 pour l&#8217;achat, la location ou la maintenance de votre \u00e9quipement Xerox et Lexmark.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]<div id=\"wd-6942dc7e115bc\" class=\" wd-rs-6942dc7e115bc  wd-button-wrapper text-left\"><a href=\"\/fr\/contact\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">Contactez-nous<\/a><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6a4e0761e394f\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0761e394f wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Les \u00e9quipements Xerox et Lexmark : Une gamme compl\u00e8te pour tous les professionnels<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]En choisissant aussi bien Xerox que Lexmark, vous optez pour des \u00e9quipements reconnus pour leur robustesse, leur qualit\u00e9 d&#8217;impression constante (couleur ou N&amp;B) et leurs interfaces modernes. D&amp;O Partners vous propose l&#8217;ensemble de la gamme pour couvrir tous les besoins de votre entreprise en <strong>Belgique<\/strong> :<\/p>\n<ul>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/categorie-produits\/systemes-impression\/imprimantes-bureau\/\">Imprimantes de bureau<\/a> : id\u00e9ales pour les petites \u00e9quipes et le t\u00e9l\u00e9travail, elles offrent simplicit\u00e9 et productivit\u00e9 avec Wi-Fi, impression recto-verso automatique et qualit\u00e9 professionnelle.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/categorie-produits\/systemes-impression\/multifonctions\/\">Imprimantes multifonctions \/ tout-en-un<\/a> : appareil polyvalent qui centralise l\u2019impression, la copie, la num\u00e9risation et le fax. C\u2019est la solution la plus efficace pour r\u00e9duire les co\u00fbts et optimiser les flux documentaires.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/categorie-produits\/systemes-impression\/production-presse-numerique\/\">Imprimantes de production<\/a> : pour les volumes tr\u00e8s \u00e9lev\u00e9s et les exigences de qualit\u00e9 avanc\u00e9es (communication graphique, \u00e9dition), les presses num\u00e9riques Xerox offrent une disponibilit\u00e9 et une productivit\u00e9 remarquables.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/imprimantes-et-consommables\/imprimante-xerox-versalink\/\">Imprimantes connect\u00e9es VersaLink<\/a> : nouvelle g\u00e9n\u00e9ration de multifonctions laser A4 et A3, tous \u00e9quip\u00e9s de la technologie prim\u00e9e ConnectKey. Elle assure des int\u00e9grations de flux de travail flexibles, des performances \u00e9lev\u00e9es et une s\u00e9curit\u00e9 maximale pour les environnements modernes (incluant les s\u00e9ries C415, C625, B625 et A3 C7100\/B7100).<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/imprimantes-et-consommables\/imprimantes-xerox-altalink\/\">Imprimantes connect\u00e9es AltaLink<\/a> : con\u00e7ue pour les PME et les environnements intensifs, cette gamme propose des multifonctions A3\/A4 performants dot\u00e9s d\u2019une automatisation avanc\u00e9e des flux, d\u2019une s\u00e9curit\u00e9 intelligente et de la technologie ConnectKey. Elle int\u00e8gre une interface tactile intuitive et une connectivit\u00e9 cloud (s\u00e9ries 8100 et 8200).<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/imprimantes-et-consommables\/imprimantes-xerox-primelink\/\">Imprimantes connect\u00e9es PrimeLink<\/a> : cr\u00e9\u00e9e pour les entreprises traitant de grands volumes, ces imprimantes multifonctions A3 offrent une fiabilit\u00e9 maximale, une vitesse \u00e9lev\u00e9e et une qualit\u00e9 professionnelle. Alliant performances quasi industrielles et flexibilit\u00e9 ConnectKey, elles s\u2019adaptent \u00e0 la production comme au bureau moderne.<\/li>\n<li><a class=\"underline underline underline-offset-2 decoration-1 decoration-current\/40 hover:decoration-current focus:decoration-current\" href=\"https:\/\/www.dopartners.be\/fr\/produit\/imprimantes-multifonctions-couleur-lexmark-serie-cx95\/\">Imprimantes multifonctions Lexmark<\/a> : en tant que dealer officiel Lexmark, D&amp;O Partners propose \u00e9galement les gammes CX (multifonctions couleur A3, s\u00e9ries CX95\/CX96) et MX (multifonctions monochromes, s\u00e9rie MX95). Reconnues pour leur robustesse, leur s\u00e9curit\u00e9 renforc\u00e9e et leurs outils de gestion documentaire avanc\u00e9s, elles conviennent particuli\u00e8rement aux environnements professionnels exigeants o\u00f9 fiabilit\u00e9 et ma\u00eetrise des co\u00fbts sont prioritaires.<\/li>\n<\/ul>\n<p>Nous vous aidons \u00e0 s\u00e9lectionner le mod\u00e8le Xerox ou Lexmark adapt\u00e9 \u00e0 votre volume mensuel, au type de vos documents et \u00e0 vos contraintes d\u2019espace.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]<div id=\"wd-6a4e441e0a6f3\" class=\" wd-rs-6a4e441e0a6f3  wd-button-wrapper text-left\"><a href=\"\/fr\/imprimantes-et-consommables\/\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">Nos imprimantes Xerox et Lexmark pour professionnels<\/a><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6a4e18419c9fc\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e18419c9fc wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Solutions logicielles et connectivit\u00e9 pour vos photocopieurs Xerox et Lexmark<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Au-del\u00e0 du mat\u00e9riel (Hardware), les imprimantes multifonctions Xerox int\u00e8grent diff\u00e9rentes technologies connect\u00e9es (ConnectKey, Workflow Central, cloud&#8230;) pour la gestion de votre entreprise au quotidien. D&amp;O Partners vous propose des solutions logicielles (software) pour d\u00e9cupler la productivit\u00e9 de votre activit\u00e9 en <strong>Belgique<\/strong>.<\/p>\n<p>Ces applications permettent :<\/p>\n<ul>\n<li>L\u2019automatisation des t\u00e2ches : gagnez du temps en automatisant les flux de travail.<\/li>\n<li>La gestion documentaire : g\u00e9rez et archivez l&#8217;information de mani\u00e8re s\u00e9curis\u00e9e et efficace.<\/li>\n<li>L&#8217;int\u00e9gration cloud : connectez votre photocopieur \u00e0 vos outils cloud courants.<\/li>\n<li>La s\u00e9curit\u00e9 avanc\u00e9e : nos imprimantes professionnelles int\u00e8grent des m\u00e9canismes de s\u00e9curit\u00e9 de derni\u00e8re g\u00e9n\u00e9ration (authentification utilisateur, protections du disque).<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]<div id=\"wd-6942ddb2b864c\" class=\" wd-rs-6942ddb2b864c  wd-button-wrapper text-left\"><a href=\"\/fr\/solutions\/\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">Nos solutions software d&#039;impression<\/a><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6942ddc659d36\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6942ddc659d36 wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Nos services : L'accompagnement local D&amp;O Partners<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Avec plus de 30 ans d&#8217;exp\u00e9rience, D&amp;O Partners propose un service global et personnalis\u00e9, faisant de nous un acteur cl\u00e9 de <strong>Xerox et Lexmark en Belgique<\/strong>. Nous accompagnons les entreprises sur tout le cycle de vie de leur \u00e9quipement : de l\u2019installation des machines et des applications, \u00e0 la maintenance technique et le r\u00e9assort de consommables.<\/p>\n<ul>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/services\/financement-location\/\">Location et financement (leasing op\u00e9rationnel)<\/a> : nous vous proposons des solutions pour acheter une solution durable ou louer un photocopieur r\u00e9cent avec un budget liss\u00e9 et de la flexibilit\u00e9.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/services\/service-premium\/\">Installation et mise en service<\/a> : nous assurons la mise en service, la configuration r\u00e9seau et la prise en main compl\u00e8te de vos \u00e9quipes pour un d\u00e9marrage fluide. Nous configurons le scan vers e-mail\/dossier, les r\u00e8gles d\u2019impression, l\u2019authentification et les pilotes sur postes.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/services\/service-technique-consommables\/\">Maintenance et support technique Xerox<\/a> : nos techniciens form\u00e9s en continu par Xerox interviennent rapidement sur Bruxelles et sa p\u00e9riph\u00e9rie pour diagnostiquer et r\u00e9soudre pannes et probl\u00e8mes de configuration. Nous proposons un support \u00e0 distance (TeamViewer) pour une prise en charge s\u00e9curis\u00e9e et rapide.<\/li>\n<li><a href=\"https:\/\/www.dopartners.be\/fr\/categorie-produits\/consommables\/\">Consommables (toutes marques)<\/a> : nous regroupons l&#8217;ensemble de vos consommables (papier, toner, cartouches, SmartKit, etc.) pour Xerox, Lexmark et autres marques (HP, Brother, Canon). Cela permet d&#8217;\u00e9viter les ruptures et de r\u00e9duire les co\u00fbts.<\/li>\n<\/ul>\n<p>[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]<div id=\"wd-6942dde541aa1\" class=\" wd-rs-6942dde541aa1  wd-button-wrapper text-left\"><a href=\"\/fr\/services\/\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">Nos services d&#039;impression<\/a><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6a4e0a583848e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0a583848e wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Pourquoi choisir D&amp;O Partners : Le choix de la gamme Xerox et Lexmark<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\n<p class=\"font-claude-response-body break-words whitespace-normal\">Depuis 1992, notre expertise s&#8217;appuie sur des piliers fondamentaux pour votre entreprise en Belgique, renforc\u00e9s aujourd&#8217;hui par notre statut de dealer officiel Xerox et Lexmark (appareils, imprimantes, copieurs, multifonctions, presses de production) :<\/p>\n<ul class=\"[li_&amp;]:mb-0 [li_&amp;]:mt-1 [li_&amp;]:gap-1 [&amp;:not(:last-child)_ul]:pb-1 [&amp;:not(:last-child)_ol]:pb-1 list-disc flex flex-col gap-1 pl-8 mb-3\">\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Fiabilit\u00e9 et innovation Xerox et Lexmark<\/strong> : les \u00e9quipements des deux marques sont reconnus pour leur robustesse, la qualit\u00e9 d&#8217;impression constante et leurs interfaces personnalisables. Les applications embarqu\u00e9es et fonctionnalit\u00e9s connect\u00e9es (Wi-Fi, impression mobile) boostent la productivit\u00e9, avec en plus, chez Lexmark, des fonctionnalit\u00e9s de s\u00e9curit\u00e9 avanc\u00e9e particuli\u00e8rement adapt\u00e9es aux environnements exigeants.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Une offre compl\u00e8te et coh\u00e9rente<\/strong> : de l&#8217;imprimante de bureau compacte \u00e0 la presse de production, la largeur combin\u00e9e des gammes Xerox et Lexmark permet de r\u00e9pondre pr\u00e9cis\u00e9ment \u00e0 vos besoins en mati\u00e8re de capacit\u00e9 papier, de vitesse, de s\u00e9curit\u00e9 et de gestion documentaire.<\/li>\n<li class=\"font-claude-response-body whitespace-normal break-words pl-2\"><strong>Accompagnement local et expertise<\/strong> : notre \u00e9quipe locale vous conseille et prend en charge l&#8217;audit, le choix du mat\u00e9riel \u2014 Xerox ou Lexmark selon vos besoins \u2014 le d\u00e9ploiement et la maintenance. Nous privil\u00e9gions des configurations simples \u00e0 administrer et faciles \u00e0 utiliser au quotidien.<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6a4e0b1d9fb6e\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0b1d9fb6e wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >Contactez votre sp\u00e9cialiste Xerox et Lexmark en Belgique<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Vous souhaitez moderniser votre parc, r\u00e9duire vos co\u00fbts ou am\u00e9liorer vos workflows documentaires avec un \u00e9quipement Xerox ou Lexmark ? Notre \u00e9quipe D&amp;O Partners est \u00e0 votre disposition.<\/p>\n<ul>\n<li><strong>Adresse<\/strong> : 530-534 Avenue de la Couronne 1050 Bruxelles<\/li>\n<li><strong>T\u00e9l\u00e9phone (Standard)<\/strong> : +32 (0)2 643 42 42<\/li>\n<li><strong>Horaires<\/strong> : Lundi au vendredi 08:30 \u2013 17:00. Ferm\u00e9 samedi et dimanche<\/li>\n<\/ul>\n<p>Nous intervenons rapidement dans toutes les communes de la R\u00e9gion de <strong>Bruxelles-Capitale<\/strong> : Anderlecht, Auderghem, Berchem-Sainte-Agathe, Bruxelles-Ville, Etterbeek, Evere, Forest, Ganshoren, Ixelles, Jette, Koekelberg, Molenbeek-Saint-Jean, Saint-Gilles, Saint-Josse-ten-Noode, Schaerbeek, Uccle, Watermael-Boitsfort, Woluwe-Saint-Lambert, Woluwe-Saint-Pierre. Nous nous rendons \u00e9galement disponibles partout en Belgique.[\/vc_column_text][vc_empty_space height=&#8221;20px&#8221; woodmart_hide_large=&#8221;0&#8243; woodmart_hide_medium=&#8221;0&#8243; woodmart_hide_small=&#8221;0&#8243;]<div id=\"wd-6942de50dd6db\" class=\" wd-rs-6942de50dd6db  wd-button-wrapper text-left\"><a href=\"\/fr\/contact\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">Contactez-nous<\/a><\/div>[\/vc_column][\/vc_row][vc_row css=&#8221;.vc_custom_1713945594502{margin-bottom: 5vh !important;}&#8221; el_class=&#8221;txt_service&#8221; woodmart_css_id=&#8221;6628bbf6677d1&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2NjI4YmJmNjY3N2QxIiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243;][vc_column 0=&#8221;&#8221;]\n\t\t<div id=\"wd-6942de6b127aa\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6942de6b127aa wd-title-color-primary wd-title-style-underlined text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h2 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-xl\" >FAQ<\/h2>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t\n\t\t<div id=\"wd-6a4e0b3d2019f\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0b3d2019f wd-title-color-primary wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Comment D&amp;O Partners peut-il m'aider \u00e0 choisir le bon photocopieur Xerox et\/ou Lexmark ?<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Nous \u00e9valuons votre volume mensuel (impressions\/copies), le taux de couleur et le type de supports, ainsi que les contraintes d&#8217;espace pour dimensionner la vitesse et la capacit\u00e9 papier. Contactez-nous pour une recommandation personnalis\u00e9e.<br \/>\n[\/vc_column_text]\n\t\t<div id=\"wd-6942de95c7e5f\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6942de95c7e5f wd-title-color-primary wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Intervenez-vous pour le support technique dans toute la Belgique ?<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Nos techniciens couvrent l&#8217;ensemble de la Belgique. Pour une demande de support technique machine en panne, vous devez appeler le +32 (0)2 713 14 52 si votre contrat n&#8217;inclut pas XPPS. Pour une configuration ou une connexion, contactez le standard au +32 (0)2 643 42 42.[\/vc_column_text]\n\t\t<div id=\"wd-6a4e0b5975d4f\" class=\"title-wrapper wd-wpb wd-set-mb reset-last-child  wd-rs-6a4e0b5975d4f wd-title-color-primary wd-title-style-default text-left  wd-underline-colored\">\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title  wd-font-weight- wd-fontsize-m\" >Fournissez-vous des consommables exclusivement pour les machines Xerox et Lexmark ?<\/h3>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\n\t\t[vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]Non. En plus de Xerox et Lexmark, nous fournissons des consommables et fournitures (papier, agrafes, etc.) pour les marques courantes comme HP, Brother, Canon, pour simplifier la gestion de votre parc existant.[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; basel_parallax=&#8221;1&#8243; css=&#8221;.vc_custom_1532665901855{margin-bottom: -40px !important;padding-top: 20px !important;padding-bottom: 20px !important;background-color: #f7f7f7 !important;background-position: center !important;background-repeat: no-repeat !important;background-size: cover !important;}&#8221;][vc_column width=&#8221;5\/6&#8243; basel_color_scheme=&#8221;light&#8221; css=&#8221;.vc_custom_1486390038165{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;][vc_custom_heading text=&#8221;Contactez-nous pour en savoir plus !&#8221; font_container=&#8221;tag:h2|font_size:32|text_align:left|color:%23000000&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1678366453184{margin-bottom: 5px !important;}&#8221;][\/vc_column][vc_column width=&#8221;1\/6&#8243; css=&#8221;.vc_custom_1486390042993{padding-top: 20px !important;padding-bottom: 20px !important;}&#8221;]<div id=\"wd-6a56d88fe0cb3\" class=\"  wd-button-wrapper text-center\"><a href=\"\/fr\/contact\" title=\"\" class=\"btn btn-color-primary btn-style-default btn-shape-rectangle btn-size-large\">CONTACT<\/a><\/div>[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row full_width=&#8221;stretch_row&#8221; content_placement=&#8221;middle&#8221; woodmart_stretch_content=&#8221;section-stretch&#8221; woodmart_bg_position=&#8221;center-center&#8221; el_class=&#8221;hero_title&#8221; woodmart_css_id=&#8221;68d296fe6faf4&#8243; responsive_spacing=&#8221;eyJwYXJhbV90eXBlIjoid29vZG1hcnRfcmVzcG9uc2l2ZV9zcGFjaW5nIiwic2VsZWN0b3JfaWQiOiI2OGQyOTZmZTZmYWY0Iiwic2hvcnRjb2RlIjoidmNfcm93IiwiZGF0YSI6eyJ0YWJsZXQiOnt9LCJtb2JpbGUiOnt9fX0=&#8221; mobile_bg_img_hidden=&#8221;no&#8221; tablet_bg_img_hidden=&#8221;no&#8221; woodmart_parallax=&#8221;0&#8243; woodmart_gradient_switch=&#8221;no&#8221; woodmart_box_shadow=&#8221;no&#8221; wd_z_index=&#8221;no&#8221; woodmart_disable_overflow=&#8221;0&#8243; row_reverse_mobile=&#8221;0&#8243; row_reverse_tablet=&#8221;0&#8243; css=&#8221;.vc_custom_1758631722955{background-image: url(https:\/\/www.dopartners.be\/wp-content\/uploads\/2024\/06\/revolution-xerographique-2-xerox-belgique-dopartners.webp?id=8829) !important;background-position:<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-8464","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Solutions d&#039;impression Xerox Belgique - Vente, location &amp; support<\/title>\n<meta name=\"description\" content=\"D&amp;O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solutions d&#039;impression Xerox Belgique - Vente, location &amp; support\" \/>\n<meta property=\"og:description\" content=\"D&amp;O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/\" \/>\n<meta property=\"og:site_name\" content=\"D&amp;O Partners\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DOPartnersXerox\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-08T12:35:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"135\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/\",\"url\":\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/\",\"name\":\"Solutions d'impression Xerox Belgique - Vente, location & support\",\"isPartOf\":{\"@id\":\"https:\/\/www.dopartners.be\/fr\/#website\"},\"datePublished\":\"2024-04-24T08:12:59+00:00\",\"dateModified\":\"2026-07-08T12:35:56+00:00\",\"description\":\"D&O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dopartners.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Xerox Belgique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dopartners.be\/fr\/#website\",\"url\":\"https:\/\/www.dopartners.be\/fr\/\",\"name\":\"D&amp;O Partners\",\"description\":\"Concessionnaire Xerox autoris\u00e9 \u00e0 Bruxelles\",\"publisher\":{\"@id\":\"https:\/\/www.dopartners.be\/fr\/#organization\"},\"alternateName\":\"DO Partners\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dopartners.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dopartners.be\/fr\/#organization\",\"name\":\"DO PARTNERS\",\"url\":\"https:\/\/www.dopartners.be\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\/\/www.dopartners.be\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png\",\"contentUrl\":\"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png\",\"width\":135,\"height\":100,\"caption\":\"DO PARTNERS\"},\"image\":{\"@id\":\"https:\/\/www.dopartners.be\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DOPartnersXerox\",\"https:\/\/www.youtube.com\/@dopartners\",\"https:\/\/www.linkedin.com\/company\/d&amp;o-partners\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solutions d'impression Xerox Belgique - Vente, location & support","description":"D&O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/","og_locale":"fr_FR","og_type":"article","og_title":"Solutions d'impression Xerox Belgique - Vente, location & support","og_description":"D&O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.","og_url":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/","og_site_name":"D&amp;O Partners","article_publisher":"https:\/\/www.facebook.com\/DOPartnersXerox","article_modified_time":"2026-07-08T12:35:56+00:00","og_image":[{"width":135,"height":100,"url":"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/","url":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/","name":"Solutions d'impression Xerox Belgique - Vente, location & support","isPartOf":{"@id":"https:\/\/www.dopartners.be\/fr\/#website"},"datePublished":"2024-04-24T08:12:59+00:00","dateModified":"2026-07-08T12:35:56+00:00","description":"D&O Partners, votre partenaire Xerox en Belgique \u00e0 Bruxelles : vente, location, installation et maintenance de photocopieurs professionnels Xerox.","breadcrumb":{"@id":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dopartners.be\/fr\/xerox-belgique\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dopartners.be\/fr\/xerox-belgique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dopartners.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Xerox Belgique"}]},{"@type":"WebSite","@id":"https:\/\/www.dopartners.be\/fr\/#website","url":"https:\/\/www.dopartners.be\/fr\/","name":"D&amp;O Partners","description":"Concessionnaire Xerox autoris\u00e9 \u00e0 Bruxelles","publisher":{"@id":"https:\/\/www.dopartners.be\/fr\/#organization"},"alternateName":"DO Partners","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dopartners.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"},{"@type":"Organization","@id":"https:\/\/www.dopartners.be\/fr\/#organization","name":"DO PARTNERS","url":"https:\/\/www.dopartners.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/www.dopartners.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png","contentUrl":"https:\/\/www.dopartners.be\/wp-content\/uploads\/2017\/11\/DO-partners-logo.png","width":135,"height":100,"caption":"DO PARTNERS"},"image":{"@id":"https:\/\/www.dopartners.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DOPartnersXerox","https:\/\/www.youtube.com\/@dopartners","https:\/\/www.linkedin.com\/company\/d&amp;o-partners\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/pages\/8464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/comments?post=8464"}],"version-history":[{"count":0,"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/pages\/8464\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.dopartners.be\/fr\/wp-json\/wp\/v2\/media?parent=8464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}